{"id":49884,"date":"2024-12-02T10:09:32","date_gmt":"2024-12-02T14:09:32","guid":{"rendered":"https:\/\/loveoporaqui.com\/web1\/?p=49884"},"modified":"2024-12-02T10:09:32","modified_gmt":"2024-12-02T14:09:32","slug":"fallece-la-actriz-sandra-reyes-recordada-por-su-papel-de-la-dra-paula-en-pedro-el-escamoso","status":"publish","type":"post","link":"https:\/\/loveoporaqui.com\/web1\/fallece-la-actriz-sandra-reyes-recordada-por-su-papel-de-la-dra-paula-en-pedro-el-escamoso\/","title":{"rendered":"Fallece la actriz Sandra Reyes, recordada por su papel de la \u201cDra. Paula\u201d en \u201cPedro el escamoso"},"content":{"rendered":"<p data-mrf-recirculation=\"PrimeraHora - Article Body\">La destacada actriz colombiana,\u00a0<b>Sandra Reyes<\/b>, conocida por su papel de la doctora Paula D\u00e1vila en \u2018Pedro, el escamoso\u2019 y como la madre de \u2018Rigo\u2019, en la novela biogr\u00e1fica del ciclista Rigoberto Ur\u00e1n,\u00a0<b>falleci\u00f3 este domingo<\/b>, 1 de diciembre de 2024.<\/p>\n<p data-mrf-recirculation=\"PrimeraHora - Article Body\">As\u00ed lo confirm\u00f3 Noticias RCN en su edici\u00f3n del mediod\u00eda, en donde se agreg\u00f3 que la artista falleci\u00f3 en su casa acompa\u00f1ada de su familia.<\/p>\n<div id=\"carodaOutstream89301Container\" class=\"carodaContainer\">\n<div id=\"carodaOutstream89301\" class=\"carodaOutstream adLoaded format-horizontal format-big carodaOutstreamSlider\">EL TIEMPO logr\u00f3 constatar la informaci\u00f3n de la muerte de la bogotana de\u00a0<b>49 a\u00f1os<\/b>, luego de estar vigente durante m\u00e1s de veinte a\u00f1os en la televisi\u00f3n colombiana, convirti\u00e9ndola en una de las actrices m\u00e1s reconocidas y queridas de los colombianos.<\/div>\n<div>\n<p data-mrf-recirculation=\"PrimeraHora - Article Body\"><b>Cu\u00e1les son las causas de la muerte de Sandra Reyes?<\/b><\/p>\n<p data-mrf-recirculation=\"PrimeraHora - Article Body\">Reyes muri\u00f3 a causa de una<b>\u00a0larga lucha contra el c\u00e1ncer de seno<\/b>, la cual era de total reserva al p\u00fablico. Su primo, Nicol\u00e1s Reyes, resalt\u00f3 en el medio Red+ el legado art\u00edstico y humano que dej\u00f3 en la industria del entretenimiento.<\/p>\n<div class=\"ArticleBodyEmbed\"><iframe title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/4Uy08OMAWlg?si=SxkZlyx8_6l6XYDG\" width=\"570\" height=\"320.625\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n<p data-mrf-recirculation=\"PrimeraHora - Article Body\">A lo largo de su carrera, Reyes se caracteriz\u00f3 por grandes papeles protagonistas en populares telenovelas que lograron darle la vuelta al mundo como \u2018Pedro, el escamoso\u2019 en 2001, interpretando a Paula D\u00e1vila y Amparo Cadena en la serie \u2018El Cartel de los sapos\u2019 en 2008.<\/p>\n<p data-mrf-recirculation=\"PrimeraHora - Article Body\">La colombiana contin\u00fao marcando una huella en sus seguidores con el \u00faltimo papel que hizo en la producci\u00f3n basada en la vida de Rigoberto Ur\u00e1n, en la que personific\u00f3 a do\u00f1a Aracely de Ur\u00e1n, la madre del ciclista.<\/p>\n<figure class=\"ArticleBodyImage\"><picture class=\"ResponsiveImage ArticleBodyImage__photo\"><source srcset=\"https:\/\/www.primerahora.com\/resizer\/v2\/DE3FYOOOO5C7JIEOT5L66BF6VA.jpg?auth=6a9d07e815172faa68b0c2643cb1ff7f7101ad2379d706654a45612962289c24&amp;quality=75&amp;width=327&amp;height=327&amp;focal=259%2C184, https:\/\/www.primerahora.com\/resizer\/v2\/DE3FYOOOO5C7JIEOT5L66BF6VA.jpg?auth=6a9d07e815172faa68b0c2643cb1ff7f7101ad2379d706654a45612962289c24&amp;quality=75&amp;width=654&amp;height=654&amp;focal=259%2C184 2x\" media=\"(max-width: 375px)\" \/><source srcset=\"https:\/\/www.primerahora.com\/resizer\/v2\/DE3FYOOOO5C7JIEOT5L66BF6VA.jpg?auth=6a9d07e815172faa68b0c2643cb1ff7f7101ad2379d706654a45612962289c24&amp;quality=75&amp;width=719&amp;focal=259%2C184, https:\/\/www.primerahora.com\/resizer\/v2\/DE3FYOOOO5C7JIEOT5L66BF6VA.jpg?auth=6a9d07e815172faa68b0c2643cb1ff7f7101ad2379d706654a45612962289c24&amp;quality=75&amp;width=1438&amp;focal=259%2C184 2x\" media=\"(max-width: 767px)\" \/><source srcset=\"https:\/\/www.primerahora.com\/resizer\/v2\/DE3FYOOOO5C7JIEOT5L66BF6VA.jpg?auth=6a9d07e815172faa68b0c2643cb1ff7f7101ad2379d706654a45612962289c24&amp;quality=75&amp;width=873&amp;focal=259%2C184, https:\/\/www.primerahora.com\/resizer\/v2\/DE3FYOOOO5C7JIEOT5L66BF6VA.jpg?auth=6a9d07e815172faa68b0c2643cb1ff7f7101ad2379d706654a45612962289c24&amp;quality=75&amp;width=1746&amp;focal=259%2C184 2x\" media=\"(max-width: 1023px)\" \/><source srcset=\"https:\/\/www.primerahora.com\/resizer\/v2\/DE3FYOOOO5C7JIEOT5L66BF6VA.jpg?auth=6a9d07e815172faa68b0c2643cb1ff7f7101ad2379d706654a45612962289c24&amp;quality=75&amp;width=1280&amp;focal=259%2C184, https:\/\/www.primerahora.com\/resizer\/v2\/DE3FYOOOO5C7JIEOT5L66BF6VA.jpg?auth=6a9d07e815172faa68b0c2643cb1ff7f7101ad2379d706654a45612962289c24&amp;quality=75&amp;width=2560&amp;focal=259%2C184 2x\" media=\"(max-width: 1440px)\" \/><source srcset=\"https:\/\/www.primerahora.com\/resizer\/v2\/DE3FYOOOO5C7JIEOT5L66BF6VA.jpg?auth=6a9d07e815172faa68b0c2643cb1ff7f7101ad2379d706654a45612962289c24&amp;quality=75&amp;width=1800&amp;focal=259%2C184, https:\/\/www.primerahora.com\/resizer\/v2\/DE3FYOOOO5C7JIEOT5L66BF6VA.jpg?auth=6a9d07e815172faa68b0c2643cb1ff7f7101ad2379d706654a45612962289c24&amp;quality=75&amp;width=3600&amp;focal=259%2C184 2x\" media=\"(max-width: 1920px)\" \/><source srcset=\"https:\/\/www.primerahora.com\/resizer\/v2\/DE3FYOOOO5C7JIEOT5L66BF6VA.jpg?auth=6a9d07e815172faa68b0c2643cb1ff7f7101ad2379d706654a45612962289c24&amp;quality=75&amp;width=2560&amp;focal=259%2C184, https:\/\/www.primerahora.com\/resizer\/v2\/DE3FYOOOO5C7JIEOT5L66BF6VA.jpg?auth=6a9d07e815172faa68b0c2643cb1ff7f7101ad2379d706654a45612962289c24&amp;quality=75&amp;width=5120&amp;focal=259%2C184 2x\" \/><img decoding=\"async\" class=\"ResponsiveImage__img\" src=\"https:\/\/www.primerahora.com\/resizer\/v2\/DE3FYOOOO5C7JIEOT5L66BF6VA.jpg?auth=6a9d07e815172faa68b0c2643cb1ff7f7101ad2379d706654a45612962289c24&amp;quality=75&amp;width=2560&amp;focal=259%2C184\" alt=\"Miguel Varoni despidi\u00f3 a Sandra Reyes,\" \/><\/picture><figcaption class=\"ArticleBodyImage__caption\">Miguel Varoni despidi\u00f3 a Sandra Reyes,\u00a0<span class=\"Caption__credit\">(Instagram)<\/span><\/figcaption><\/figure>\n<p data-mrf-recirculation=\"PrimeraHora - Article Body\">Los detalles conocidos acerca de su fallecimiento se enfocaron en que la famosa manej\u00f3 su enfermedad como un asunto en privado y de completa reserva, evitando que saliera a la luz. Tras morir, su cuerpo ser\u00e1 trasladado a una finca en Ubat\u00e9, donde habr\u00e1 una despedida \u00edntima con sus seres amados.<\/p>\n<p data-mrf-recirculation=\"PrimeraHora - Article Body\">La noticia sorprendi\u00f3 a sus seguidores y aquellos que la vieron triunfar en una gran cantidad de novelas, con las que gan\u00f3 apoyo.<\/p>\n<p data-mrf-recirculation=\"PrimeraHora - Article Body\"><b>Miguel Varoni<\/b>, actor y director de televisi\u00f3n colombiano, conocido por de forma internacional por actuar como Pedro Coral Tavera en la serie \u2018Pedro, el Escamoso\u2019, fue uno de los primeros en pronunciarse sobre el lamentable hecho y dej\u00f3 un sentido mensaje en su cuenta en la red social de Instagram.<\/p>\n<div data-threshold=\"1.5\" data-slot=\"intxtad_2\">\n<div id=\"intxtElement\">\n<p id=\"intxtPElement\" data-mrf-recirculation=\"PrimeraHora - Article Body\">PUBLICIDAD<\/p>\n<div id=\"intxtad_2\" data-ad=\"intxtad\" data-google-query-id=\"CJ6wuYOhiYoDFRaMywEd8SsmwA\">\n<div id=\"google_ads_iframe_\/282897603\/primerahora.com\/entretenimiento\/intxtad_2_0__container__\"><iframe id=\"google_ads_iframe_\/282897603\/primerahora.com\/entretenimiento\/intxtad_2_0\" tabindex=\"0\" title=\"3rd party ad content\" name=\"google_ads_iframe_\/282897603\/primerahora.com\/entretenimiento\/intxtad_2_0\" width=\"300\" height=\"250\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" aria-label=\"Advertisement\" data-load-complete=\"true\" data-google-container-id=\"9\"><\/iframe><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p data-mrf-recirculation=\"PrimeraHora - Article Body\">\u201cHasta siempre mi Doctora Paula\u201d, comenz\u00f3 diciendo en una publicaci\u00f3n. Con cortas palabras y una fotograf\u00eda antigua de ambos interpretando a sus personajes, escribi\u00f3: \u201cSumerce no sabe la falta que me va a hacer. Dios me la Bendiga. Siempre estar en mi coraz\u00f3n\u2026\u201d.<\/p>\n<div class=\"ArticleBodyEmbed\"><iframe id=\"instagram-embed-1\" class=\"instagram-media instagram-media-rendered\" src=\"https:\/\/www.instagram.com\/p\/DDC-1JsRoV2\/embed\/captioned\/?cr=1&amp;v=14&amp;wp=540&amp;rd=https%3A%2F%2Fwww.primerahora.com&amp;rp=%2Fentretenimiento%2Ffarandula%2Fnotas%2Ffallece-la-actriz-sandra-reyes-recordada-por-su-papel-de-la-dra-paula-en-pedro-el-escamoso%2F#%7B%22ci%22%3A1%2C%22os%22%3A10748.600000000006%2C%22ls%22%3A302.70000000001164%2C%22le%22%3A523.3000000000175%7D\" height=\"620\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-instgrm-payload-id=\"instagram-media-payload-1\"><\/iframe><\/div>\n<p data-mrf-recirculation=\"PrimeraHora - Article Body\">Con esto, el actor se despidi\u00f3 de la que fue tambi\u00e9n su amiga fuera de los sets de grabaci\u00f3n. Vale recordar que Varoni y Reyes se volvieron a encontrar en la segunda temporada de \u2018Pedro el Escamoso\u2019, la cual se estren\u00f3 este a\u00f1o por la plataforma Disney+ y emitida tambi\u00e9n en el canal Caracol.<\/p>\n<p data-mrf-recirculation=\"PrimeraHora - Article Body\">Desde muy joven, Sandra Reyes incursion\u00f3 en la industria actoral, destacando por su carisma y talento frente a las c\u00e1maras de la televisi\u00f3n. Sus papeles en estos formatos la catapultaron como una de las actrices m\u00e1s queridas del pa\u00eds.<\/p>\n<p data-mrf-recirculation=\"PrimeraHora - Article Body\">A pesar de ser tan conocida, la actriz no compart\u00eda muchos detalles de su vida personal en sus redes sociales. De hecho, en sus publicaciones siempre mostraba su conexi\u00f3n con la naturaleza y todo lo relacionado con su trabajo.<\/p>\n<p data-mrf-recirculation=\"PrimeraHora - Article Body\">Ella misma se describ\u00eda en su perfil como \u201cHippie recordatriz de bruja\u201d y amante del arte, de la pintura y la actuaci\u00f3n.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La destacada actriz colombiana,\u00a0Sandra Reyes, conocida por su papel de la doctora Paula D\u00e1vila en \u2018Pedro, el escamoso\u2019 y como la madre de \u2018Rigo\u2019, en la novela biogr\u00e1fica del ciclista Rigoberto Ur\u00e1n,\u00a0falleci\u00f3 este domingo, 1 de diciembre de 2024. As\u00ed lo confirm\u00f3 Noticias RCN en su edici\u00f3n del mediod\u00eda, en donde se agreg\u00f3 que la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":49885,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[311],"tags":[],"class_list":["post-49884","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-al-dia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/loveoporaqui.com\/web1\/wp-content\/uploads\/2024\/12\/sandra-reyes-pedro-escamoso-miguel-varoni.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/posts\/49884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/comments?post=49884"}],"version-history":[{"count":1,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/posts\/49884\/revisions"}],"predecessor-version":[{"id":49886,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/posts\/49884\/revisions\/49886"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/media\/49885"}],"wp:attachment":[{"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/media?parent=49884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/categories?post=49884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/tags?post=49884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}