{"id":46537,"date":"2018-02-05T14:30:01","date_gmt":"2018-02-05T18:30:01","guid":{"rendered":"http:\/\/loveoporaqui.com\/web1\/?p=46537"},"modified":"2018-02-05T21:19:39","modified_gmt":"2018-02-06T01:19:39","slug":"esta-proxima-funcion-convertira-a-instagram-en-otro-whatsapp-internesis-con-jacky-fontanez","status":"publish","type":"post","link":"https:\/\/loveoporaqui.com\/web1\/esta-proxima-funcion-convertira-a-instagram-en-otro-whatsapp-internesis-con-jacky-fontanez\/","title":{"rendered":"Esta pr\u00f3xima funci\u00f3n convertir\u00e1 a Instagram en otro WhatsApp, Internesis con Jacky Font\u00e1nez"},"content":{"rendered":"<p>Por esto, pronto la apuesta ser\u00eda ofrecer videollamadas, como las que ya tiene disponibles su aplicaci\u00f3n hermana WhatsApp. Este cambio, seg\u00fan explica la gente de\u00a0<em><strong>WABetainfo<\/strong><\/em>, lo ped\u00edan muchos usuarios y ahora qued\u00f3 descubierto a trav\u00e9s de una captura de pantalla que destaca el \u00edcono de la c\u00e1mara en la barra superior de Instagram, muy parecido a como aparece en WhatsApp.<\/p>\n<p>La captura de pantalla es de iOS, pero el cambio estar\u00eda disponible para todas las plataformas y ser\u00e1 compatible sin importar si tengo iPhone o Android; sin embargo, lo m\u00e1s posible es que los usuarios tendr\u00e1n que pedirles autorizaci\u00f3n a otros para que se inicie la conversaci\u00f3n.<\/p>\n<p>\u201cEsto quiere decir que para que el icono de videollamada est\u00e9 disponible hemos de solicitar un chat a otro usuario y que este acepte la solicitud\u201d, explica Andro4all.<\/p>\n<p>Sobre el uso de la nueva funci\u00f3n, ese blog agrega que solo se deber\u00e1 presionar el bot\u00f3n de la c\u00e1mara desde un chat para realizar al videollamada; el servicio quedar\u00e1 activado tan pronto el receptor acepte el llamado.<\/p>\n<p>Por ahora, la caracter\u00edstica se encuentra en desarrollo, pero se convertir\u00e1 en una de las grandes novedades que veremos este a\u00f1o en la red social de fotograf\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por esto, pronto la apuesta ser\u00eda ofrecer videollamadas, como las que ya tiene disponibles su aplicaci\u00f3n hermana WhatsApp. Este cambio, seg\u00fan explica la gente de\u00a0WABetainfo, lo ped\u00edan muchos usuarios y ahora qued\u00f3 descubierto a trav\u00e9s de una captura de pantalla que destaca el \u00edcono de la c\u00e1mara en la barra superior de Instagram, muy parecido [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":46540,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[27],"tags":[],"class_list":["post-46537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internesis"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/loveoporaqui.com\/web1\/wp-content\/uploads\/2018\/02\/InstaWhatsApp_Project.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/posts\/46537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/comments?post=46537"}],"version-history":[{"count":1,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/posts\/46537\/revisions"}],"predecessor-version":[{"id":46538,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/posts\/46537\/revisions\/46538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/media\/46540"}],"wp:attachment":[{"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/media?parent=46537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/categories?post=46537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/tags?post=46537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}