{"id":38155,"date":"2015-07-27T09:58:11","date_gmt":"2015-07-27T13:58:11","guid":{"rendered":"http:\/\/loveoporaqui.com\/web1\/?p=38155"},"modified":"2015-07-27T10:01:20","modified_gmt":"2015-07-27T14:01:20","slug":"aleyda-ortiz-duena-de-un-corazon-maduro","status":"publish","type":"post","link":"https:\/\/loveoporaqui.com\/web1\/aleyda-ortiz-duena-de-un-corazon-maduro\/","title":{"rendered":"[VIDEO] Aleyda Ortiz :Due\u00f1a de un coraz\u00f3n maduro&#8230;La Entrevista"},"content":{"rendered":"<p>\n\t<a href=\"https:\/\/loveoporaqui.com\/web1\/wp-content\/uploads\/2015\/05\/aleyda-gif.gif\"><img fetchpriority=\"high\" decoding=\"async\" alt=\"aleyda gif\" class=\"alignleft size-full wp-image-35675\" height=\"456\" src=\"https:\/\/loveoporaqui.com\/web1\/wp-content\/uploads\/2015\/05\/aleyda-gif.gif\" width=\"808\" \/><\/a><span style=\"font-size: 14px;\"><strong>POR: AMNELLYS RIVERA<\/strong><\/span>\n<\/p>\n<p>\n\t<span style=\"font-size: 14px;\">&ldquo;Una joven de mente realista que quiere crear su propio camino&rdquo;. As&iacute; es Aleyda Ortiz, quien&nbsp; recientemente entreg&oacute; la corona de Nuestra Belleza Latina (Univisi&oacute;n) y se dio cuenta que ten&iacute;a un mundo por delante que estaba a merced de su prematura madurez, del deseo de convertir &nbsp;sus sue&ntilde;os en realidad y de lo que le dicta su coraz&oacute;n.<\/span>\n<\/p>\n<p>\n\t<a href=\"https:\/\/loveoporaqui.com\/web1\/wp-content\/uploads\/2015\/02\/aleyda-ortiz-y-gabriel-valenzuela_409x274.jpg\"><img decoding=\"async\" alt=\"aleyda-ortiz-y-gabriel-valenzuela_409x274\" class=\"alignleft size-medium wp-image-33666\" height=\"201\" src=\"https:\/\/loveoporaqui.com\/web1\/wp-content\/uploads\/2015\/02\/aleyda-ortiz-y-gabriel-valenzuela_409x274-300x201.jpg\" width=\"300\" srcset=\"https:\/\/loveoporaqui.com\/web1\/wp-content\/uploads\/2015\/02\/aleyda-ortiz-y-gabriel-valenzuela_409x274-300x201.jpg 300w, https:\/\/loveoporaqui.com\/web1\/wp-content\/uploads\/2015\/02\/aleyda-ortiz-y-gabriel-valenzuela_409x274-140x94.jpg 140w, https:\/\/loveoporaqui.com\/web1\/wp-content\/uploads\/2015\/02\/aleyda-ortiz-y-gabriel-valenzuela_409x274.jpg 409w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><span style=\"font-size: 14px;\">Sin embargo, aunque ese coraz&oacute;n est&aacute; ocupado por el actor colombiano Gabriel Valenzuela, con quien mantiene una relaci&oacute;n amorosa desde hace unos meses, ha sabido contenerse para ordenar sus prioridades en la vida.<\/span>\n<\/p>\n<p>\n\t<span style=\"font-size: 14px;\">&ldquo;Estoy s&uacute;per feliz. Yo nunca hab&iacute;a estado con alguien de los medios, porque yo misma no era de los medios. Para m&iacute; lo m&aacute;s importante en una relaci&oacute;n es cultivar el amor, estar estable, seguir conociendo a la persona y, sobre todo, tener tiempo de calidad. Por ahora quiero disfrutarme este amor, este noviazgo&rdquo;, asegur&oacute; Aleyda, quien demostr&oacute; que no le teme a los rumores sobre las relaciones pasadas que vivi&oacute; su novio Gabriel que incluyen acusaciones de infidelidades y desamor.<\/span>\n<\/p>\n<p>\n\t<span style=\"font-size: 14px;\">&ldquo;En una conversaci&oacute;n nos dimos cuenta que ten&iacute;amos cierta qu&iacute;mica y atracci&oacute;n. Yo estaba renuente; &eacute;l estaba m&aacute;s insistente. A m&iacute; me llamaba mucho la atenci&oacute;n porque &eacute;l ten&iacute;a una personalidad incre&iacute;ble, que no era lo que la gente ve&iacute;a. Lo que yo estaba conociendo de &eacute;l eran otras cosas que jam&aacute;s la gente ha visto de &eacute;l. Su caballerosidad, la manera de &eacute;l tratarme, de estar pendiente a los sentimientos y a la relaci&oacute;n,&nbsp; me gust&oacute; mucho. Siempre he sido bien independiente y enfocada en lo que quiero&rdquo;, explic&oacute; la boricua de 27 a&ntilde;os sobre lo que le llam&oacute; la atenci&oacute;n de su pareja a quien conoci&oacute; durante un reto en NBL.<\/span>\n<\/p>\n<p>\n\t<a href=\"https:\/\/loveoporaqui.com\/web1\/wp-content\/uploads\/2015\/04\/aleyda-y-gabriel-25_590x395.jpg\"><img decoding=\"async\" alt=\"aleyda-y-gabriel-25_590x395\" class=\"alignleft size-medium wp-image-34732\" height=\"201\" src=\"https:\/\/loveoporaqui.com\/web1\/wp-content\/uploads\/2015\/04\/aleyda-y-gabriel-25_590x395-300x201.jpg\" width=\"300\" srcset=\"https:\/\/loveoporaqui.com\/web1\/wp-content\/uploads\/2015\/04\/aleyda-y-gabriel-25_590x395-300x201.jpg 300w, https:\/\/loveoporaqui.com\/web1\/wp-content\/uploads\/2015\/04\/aleyda-y-gabriel-25_590x395-140x94.jpg 140w, https:\/\/loveoporaqui.com\/web1\/wp-content\/uploads\/2015\/04\/aleyda-y-gabriel-25_590x395.jpg 590w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><span style=\"font-size: 14px;\">&ldquo;Estoy con un hombre que me comprende y entiende los sacrificios de esta carrera. Nuestra relaci&oacute;n hasta al momento ha sido muy armoniosa. Nos parecemos en muchos aspectos y aparte de todo, nos compenetramos s&uacute;per bien Estos meses que llevamos juntos han sido incre&iacute;bles. Llegu&eacute; a&nbsp; Miami -donde todo era diferente para m&iacute;- a vivir sola, a empezar una carrera totalmente nueva &nbsp;y siento que &eacute;l me ha protegido como una ni&ntilde;a&rdquo;, a&ntilde;adi&oacute;&nbsp; la espigada boricua, quien enfrent&oacute; con &eacute;xito la vulnerabilidad de tener las manos llena en una nueva vida que le lleg&oacute; de momento en una ciudad como Miami- un lugar maravilloso donde hay de todo, &ldquo;pero hay que trabajar duro porque si t&uacute; eres bueno, yo soy mejor&rdquo;.<\/span>\n<\/p>\n<p>\n\t<span style=\"font-size: 14px;\"><strong>&iexcl;Wao, que a&ntilde;o!<\/strong><\/span>\n<\/p>\n<p>\n\t<span style=\"font-size: 14px;\">En cuanto al plano laboral, Aleyda, quien&nbsp; posee un bachillerato en Publicidad y Relaciones P&uacute;blicas, tampoco se puede quejar de su a&ntilde;o como reina de NBL, reality del que se despidi&oacute; con un show musical con el que dej&oacute; a todos boquiabiertos y demostr&oacute; que tiene madera para ser una gran artista.<\/span>\n<\/p>\n<p>\n\t<span style=\"font-size: 14px;\">&ldquo;Fue una prueba dura, pero yo quer&iacute;a cantar. Es dif&iacute;cil cantar y bailar a la misma vez porque se te va la respiraci&oacute;n. La parte de los ensayos fue algo cuesta arriba. Todav&iacute;a yo tengo cicatrices porque hac&iacute;a tiempo que yo no bailaba. Yo soy bien hiperactiva, me encanta el baile, soy de las que me gusta moverme toda&rdquo;, dijo con su acostumbrada carisma la joven de Bayam&oacute;n &nbsp;mientras&nbsp; nos adelantaba que vislumbra participar en una producci&oacute;n musical con tinte tropical que est&aacute; preparando su novio.<\/span>\n<\/p>\n<p>\n\t<span style=\"font-size: 14px;\">&ldquo;El est&aacute; trabajando un disco de salsa, he estado en el proceso y eso me inyect&oacute; las ganas de meterme m&aacute;s en la m&uacute;sica. Aunque todav&iacute;a estoy probando con que g&eacute;nero puedo hacerlo. Gabriel tiene la idea y siempre me ha dicho que hagamos algo juntos, que yo salga en sus videos. Tiene como una pel&iacute;cula de muchas ideas conmigo en su cabeza&rdquo;, cont&oacute; con los ojitos brillosos la animadora de &ldquo;S&aacute;bado Gigante&rdquo;, dejando entrever que ambos tienen muchos planes juntos y aclar&aacute;ndole a los gestos de esta servidora, que &ldquo;entre las ideas no est&aacute; casarse y tener hijos todav&iacute;a&rdquo;.<\/span>\n<\/p>\n<p>\n\t<span style=\"font-size: 14px;\">La finalista en Miss Universe Puerto Rico 2014 y en Miss Intercontinental 2013 reconoce que sin la ayuda y el asesoramiento de su amado, los nuevos proyectos que le depara el 2015 le hubiesen resultado un poco m&aacute;s cuesta arriba.<\/span>\n<\/p>\n<p>\n\t<span style=\"font-size: 14px;\">&ldquo;Ha sido un a&ntilde;o para m&iacute; que yo digo &iexcl;wao, que a&ntilde;o! Descubr&iacute; muchas cosas nuevas. Fue un a&ntilde;o de crecimiento, de encontrarme a m&iacute; misma. Un a&ntilde;o de oportunidades, de retos, de haber pasado por cosas que a nivel personal me tocaron, pero que me ayudaron a crecer. Vivo y hago y cuando me detengo a mirar hacia atr&aacute;s, digo &iexcl;wao! todo lo que he hecho, todo lo que he logrado. No solo yo, mi coraz&oacute;n ha madurado&rdquo;, asegur&oacute; Aleyda Ort&iacute;z, quien nos adelant&oacute; que en el plano laborar se quedar&aacute; trabajando con la cadena Univisi&oacute;n, y en el sentimental, &ldquo;todo bien gracias&rdquo;&hellip;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>POR: AMNELLYS RIVERA &ldquo;Una joven de mente realista que quiere crear su propio camino&rdquo;. As&iacute; es Aleyda Ortiz, quien&nbsp; recientemente entreg&oacute; la corona de Nuestra Belleza Latina (Univisi&oacute;n) y se dio cuenta que ten&iacute;a un mundo por delante que estaba a merced de su prematura madurez, del deseo de convertir &nbsp;sus sue&ntilde;os en realidad y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":35675,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[3],"tags":[],"class_list":["post-38155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tv-local"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/loveoporaqui.com\/web1\/wp-content\/uploads\/2015\/05\/aleyda-gif.gif","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/posts\/38155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/comments?post=38155"}],"version-history":[{"count":3,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/posts\/38155\/revisions"}],"predecessor-version":[{"id":38166,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/posts\/38155\/revisions\/38166"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/media\/35675"}],"wp:attachment":[{"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/media?parent=38155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/categories?post=38155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/tags?post=38155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}