{"id":18340,"date":"2013-10-11T13:18:37","date_gmt":"2013-10-11T17:18:37","guid":{"rendered":"http:\/\/loveoporaqui.com\/web\/?p=18340"},"modified":"2013-10-11T13:18:37","modified_gmt":"2013-10-11T17:18:37","slug":"anuncian-la-retirada-de-la-planta-de-carbon","status":"publish","type":"post","link":"https:\/\/loveoporaqui.com\/web1\/anuncian-la-retirada-de-la-planta-de-carbon\/","title":{"rendered":"Anuncian la Retirada de la Planta de Carb\u00f3n"},"content":{"rendered":"<p>&nbsp;<a href=\"http:\/\/loveoporaqui.com\/web\/wp-content\/uploads\/2013\/10\/Planta-de-carbon.jpg\" rel=\"\" style=\"\" target=\"\" title=\"\"><img fetchpriority=\"high\" decoding=\"async\" alt=\"Planta-de-carbon\" class=\"alignleft size-medium wp-image-18341\" height=\"201\" src=\"http:\/\/loveoporaqui.com\/web\/wp-content\/uploads\/2013\/10\/Planta-de-carbon-300x201.jpg\" style=\"\" title=\"\" width=\"300\" \/><\/a>El Sierra Club y una coalici&oacute;n en aumento de aliados locales, regionales y nacionales anunci&oacute; hoy el retiro de la planta de combusti&oacute;n carb&oacute;n n&uacute;mero 150 &mdash;un significativo hito en la campa&ntilde;a de abandono completo del carb&oacute;n para el a&ntilde;o 2030. Con el anunci&oacute; de hoy de que la Brayton Point Power Station en Massachusetts se retirar&aacute; para 2017, la campa&ntilde;a M&aacute;s All&aacute; del Carb&oacute;n del Sierra Club ha llegado al n&uacute;mero 150 de instalaciones carboneras jubiladas desde 2010.<\/p>\n<p>\tSeg&uacute;n la Clean Air Task Force, retirar 150 plantas de carb&oacute;n ayudar&aacute; anualmente a salvar las vidas de 4,000 personas, evitar 6,200 ataques al coraz&oacute;n y prevenir 66,300 ataques de asma. Adem&aacute;s nos ahorrar&aacute; a todos unos $1,900 millones en costos de salud.<\/p>\n<p style=\"text-align: center;\"><em><a href=\"http:\/\/action.sierraclub.org\/site\/R?i=sxA0hWsWV-9Dhg2FeZaUKQ\" target=\"_blank\">El Sierra Club ha hecho p&uacute;blico el anuncio por medio de un video en YouTube del grupo Nico Vega<\/a><\/em><\/p>\n<p style=\"text-align: left;\">&ldquo;La clausura de la planta de la Brayton Point Power Station es un poderoso ejemplo de c&oacute;mo el activismo local puede tener un impacto global&rdquo;, dijo Michael R. Bloomberg, fil&aacute;ntropo y alcalde de Nueva York. &ldquo;Durante los &uacute;ltimos tres a&ntilde;os, el activismo de comunidades locales &mdash;en cooperaci&oacute;n con el Sierra Club y Bloomberg Philanthropies&mdash; ha provocado la clausura de 150 plantas de carb&oacute;n, una tras otra. Seguiremos apoyando a quienes trabajan localmente en todo el pa&iacute;s para clausurar las sucias plantas de carb&oacute;n, las cuales causan la muerte de 13,000 personas cada a&ntilde;o y amenazan el futuro del planeta&rdquo;.<\/p>\n<p>\t&ldquo;Planta tras planta, comunidad tras comunidad, no s&oacute;lo estamos reduciendo la contaminaci&oacute;n de carbono en nuestro pa&iacute;s, sino tambi&eacute;n estamos salvando vidas&rdquo;, dijo Michael Brune, director ejecutivo del Sierra Club. &ldquo;Abandonando el sucio y peligroso carb&oacute;n, estamos creando nuevas oportunidades para la energ&iacute;a limpia y miles de empleos que protegen a nuestros trabajadores y a la salud p&uacute;blica. La transici&oacute;n del carb&oacute;n a la energ&iacute;a limpia transformar&aacute; nuestra econom&iacute;a estableciendo un nuevo y enorme sector que alimentar&aacute; de energ&iacute;a a nuestras comunidades sin envenenar a nuestros hijos&rdquo;.<\/p>\n<p>\t&ldquo;Nuestra coalici&oacute;n de grupos medioambientales, conservacionistas, de salud p&uacute;blica y derechos civiles ha logrado un hito que pocos cre&iacute;an que fuera posible&rdquo;, dijo Verena Owen, una veterana l&iacute;der comunitaria&nbsp; que codirige la campa&ntilde;a M&aacute;s All&aacute; del Carb&oacute;n del Sierra Club. &ldquo;En 2010, los analistas esperaban que se retiraran 30,000 megavatios de energ&iacute;a de carb&oacute;n durante la siguiente d&eacute;cada. Pero en menos de tres a&ntilde;os, la campa&ntilde;a casi ha duplicado estas predicciones, asegurando el retiro de m&aacute;s de 58,000 megavatios &mdash;m&aacute;s de un sexto de toda la capacidad energ&eacute;tica carbonera del pa&iacute;s y m&aacute;s del 25% de las plantas de carb&oacute;n existentes. Por medio del activismo de base y del poder de personas apasionadas de todo el pa&iacute;s, estamos dejando claro a la sucia y obsoleta industria carbonera que ya basta&rdquo;.<\/p>\n<p>\tLa industria carbonera se enfrenta a m&uacute;ltiples amenazas, incluyendo los crecientes costos del carb&oacute;n, el descenso de los precios de la energ&iacute;a limpia y una coalici&oacute;n de motivados activistas convencidos de abandonar el carb&oacute;n. Adem&aacute;s se las tiene que ver con la creciente exigencia nacional de confrontar la contaminaci&oacute;n procedente de las plantas de carb&oacute;n que causa la crisis clim&aacute;tica, el pilar b&aacute;sico de la estrategia clim&aacute;tica del Presidente Obama anunciada en junio. Cuando se instauren exigentes est&aacute;ndares de contaminaci&oacute;n de carbono, esta plantas deben instalar modernos m&eacute;todos de control de poluci&oacute;n o completar el abandono de la combusti&oacute;n del carb&oacute;n.<\/p>\n<p>\tDe hecho, mientras las compa&ntilde;&iacute;as el&eacute;ctricas se dan cuenta de que el carb&oacute;n es una inversi&oacute;n cada vez peor, est&aacute;n haciendo la transici&oacute;n hacia fuentes limpias y renovables de energ&iacute;a, como la solar y la e&oacute;lica. Hoy en d&iacute;a, Estados Unidos tiene instalados 60,000 megavatios de energ&iacute;a generada por el viento, suficientes para alimentar unos 15 millones de hogares. Texas produce tanta energ&iacute;a e&oacute;lica, que si este estado fuera un pa&iacute;s, ser&iacute;a el sexto generador del mundo. Mientras tanto, estados de todo el pa&iacute;s ya se benefician de la energ&iacute;a renovable. En 2012, Iowa y Dakota del Norte recibieron m&aacute;s del 20% de su energ&iacute;a del viento, y nueve estados produjeron m&aacute;s del 10% de su electricidad gracias al viento.<\/p>\n<p>\tAsimismo, este a&ntilde;o, Estados Unidos se uni&oacute; a otros tres pa&iacute;ses que cuentan con una generaci&oacute;n de 10,000 megavatios de energ&iacute;a solar, la cual es la opci&oacute;n de mayor crecimiento en nuestro pa&iacute;s. En estados como California, Carolina del Norte, Illinois y Nueva Jersey, la energ&iacute;a solar est&aacute; creando empleos locales y ofreciendo energ&iacute;a limpia y econ&oacute;mica. Este crecimiento de la energ&iacute;a limpia ha ayudado a crear m&aacute;s empleos en todo el pa&iacute;s y actualmente cuenta con casi 200,000 trabajadores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;El Sierra Club y una coalici&oacute;n en aumento de aliados locales, regionales y nacionales anunci&oacute; hoy el retiro de la planta de combusti&oacute;n carb&oacute;n n&uacute;mero 150 &mdash;un significativo hito en la campa&ntilde;a de abandono completo del carb&oacute;n para el a&ntilde;o 2030. Con el anunci&oacute; de hoy de que la Brayton Point Power Station en Massachusetts [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[13,8],"tags":[],"class_list":["post-18340","post","type-post","status-publish","format-standard","hentry","category-comunidad","category-loultimo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/posts\/18340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/comments?post=18340"}],"version-history":[{"count":0,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/posts\/18340\/revisions"}],"wp:attachment":[{"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/media?parent=18340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/categories?post=18340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loveoporaqui.com\/web1\/wp-json\/wp\/v2\/tags?post=18340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}